{"id":49,"date":"2014-08-25T12:33:27","date_gmt":"2014-08-25T04:33:27","guid":{"rendered":"http:\/\/wpst.kmu.edu.tw\/sakurailab\/?p=49"},"modified":"2014-08-25T12:33:27","modified_gmt":"2014-08-25T04:33:27","slug":"qr-code-%e5%8f%8a-autostereogram","status":"publish","type":"post","link":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/2014\/08\/25\/qr-code-%e5%8f%8a-autostereogram\/","title":{"rendered":"QR code \u53ca autostereogram"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u6240\u8cbc\u7684\u5716\u662f\u672c\u7ad9\u7684 QR code \u53ca\u7528\u9019\u500b\u505a\u6210\u7684autostereogram\u3002<\/p>\n<p><a href=\"http:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcode.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-51\" src=\"http:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcode-300x300.jpeg\" alt=\"sakurailabQRcode\" width=\"148\" height=\"148\" srcset=\"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcode-300x300.jpeg 300w, https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcode-150x150.jpeg 150w, https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcode.jpeg 312w\" sizes=\"auto, (max-width: 148px) 100vw, 148px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcodeRDS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50\" src=\"http:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcodeRDS-300x195.jpg\" alt=\"sakurailabQRcodeRDS\" width=\"300\" height=\"195\" srcset=\"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcodeRDS-300x195.jpg 300w, https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-content\/uploads\/sites\/61\/2014\/08\/sakurailabQRcodeRDS.jpg 921w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; \u6240\u8cbc\u7684\u5716\u662f\u672c\u7ad9\u7684 QR code \u53ca\u7528\u9019\u500b\u505a\u6210\u7684au &hellip; <a href=\"https:\/\/wpst.kmu.edu.tw\/sakurailab\/2014\/08\/25\/qr-code-%e5%8f%8a-autostereogram\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-49","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/posts\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":1,"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/posts\/49\/revisions"}],"predecessor-version":[{"id":52,"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/posts\/49\/revisions\/52"}],"wp:attachment":[{"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/media?parent=49"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/categories?post=49"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wpst.kmu.edu.tw\/sakurailab\/wp-json\/wp\/v2\/tags?post=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}